{"id":110675,"date":"2025-07-11T19:00:51","date_gmt":"2025-07-11T19:00:51","guid":{"rendered":"https:\/\/www.espinof.com\/actores-y-actrices\/lisa-kudrow-recuerda-como-fue-interpretar-a-phoebe-friends-era-diferente-a-mi-que-tuve-que-justificar-que-decia-mi-cabeza"},"modified":"2025-07-11T19:00:51","modified_gmt":"2025-07-11T19:00:51","slug":"lisa-kudrow-sobre-sus-dificultades-actuando-en-friends-phoebe-era-tan-diferente-a-mi-que-tuve-que-justificar-todo-lo-que-decia-en-mi-cabeza","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/07\/11\/lisa-kudrow-sobre-sus-dificultades-actuando-en-friends-phoebe-era-tan-diferente-a-mi-que-tuve-que-justificar-todo-lo-que-decia-en-mi-cabeza\/","title":{"rendered":"Lisa Kudrow sobre sus dificultades actuando en &#8216;Friends&#8217;: \u00abPhoebe era tan diferente a m\u00ed que tuve que justificar todo lo que dec\u00eda en mi cabeza\u00bb"},"content":{"rendered":"<p>Si tuvieran que escoger cu\u00e1l es su personaje preferido de &#8216;<a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/series-de-ficcion\/el-mejor-episodio-de-friends\" data-vars-post-title=\"El mejor episodio de... 'Friends'\" data-vars-post-url=\"https:\/\/www.espinof.com\/series-de-ficcion\/el-mejor-episodio-de-friends\">Friends<\/a>&#8216;, muchos espectadores no dudar\u00edan en quedarse con <strong>Phoebe Buffay<\/strong>, porque es uno de los personajes m\u00e1s entra\u00f1ables, divertidos y exc\u00e9ntricos de la historia de la televisi\u00f3n. Sin embargo, <strong>para Lisa Kudrow, interpretarla durante diez temporadas no fue sencillo<\/strong> precisamente, por mucho que pueda parecerlo por lo que vemos en pantalla.<\/p>\n<p><!-- BREAK 1 --> <\/p>\n<p>Aunque la serie sea una comedia que parece fluir con naturalidad, la propia Kudrow ha revelado que dar vida a Phoebe fue un verdadero reto para ella y que le cost\u00f3 disimular en algunos momentos.<\/p>\n<p><!-- BREAK 2 --><\/p>\n<p>As\u00ed lo ha contado en una entrevista para <a rel=\"noopener, noreferrer\" href=\"https:\/\/variety.com\/2025\/tv\/news\/parker-posey-lisa-kudrow-white-lotus-friends-1236414695\/\" data-id=\"noopener noreferrer\"><em>Variety<\/em><\/a> <strong>junto a Parker Posey<\/strong>, con quien ya coincidi\u00f3 en la pel\u00edcula &#8216;Esperando la hora&#8217; de 1997. En aquellos a\u00f1os, Kudrow ya era una superestrella gracias a &#8216;Friends&#8217; y Posey tambi\u00e9n despuntaba como nueva musa del cine indie. Ambas han destacado en televisi\u00f3n y en su reencuentro para la revista han hablado de su trayectoria y de los proyectos en los que quieren trabajar ahora.<\/p>\n<p><!-- BREAK 3 --> <\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/actores-y-actrices\/friends-no-le-dio-a-phoebe-hermana-gemela-solo-porque-fuera-divertido-cadena-tenia-cuenta-pendiente-otra-serie\" class=\"pivot-outboundlink\" data-vars-post-title=\"'Friends' no le dio a Phoebe una hermana gemela solo porque fuera divertido. La cadena ten\u00eda una cuenta pendiente con otra serie \"> <img loading=\"lazy\" alt=\"'Friends' no le dio a Phoebe una hermana gemela solo porque fuera divertido. La cadena ten\u00eda una cuenta pendiente con otra serie \" width=\"375\" height=\"142\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/lisa-kudrow-sobre-sus-dificultades-actuando-en-friends-phoebe-era-tan-diferente-a-mi-que-tuve-que-justificar-todo-lo-que-decia-en-mi-cabeza.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p>Durante la conversaci\u00f3n, Kudrow reconoci\u00f3 que <a href=\"https:\/\/www.espinof.com\/preview\/-OUn668DW_PkB8oRPowC\">le encantar\u00eda formar parte del elenco de &#8216;The White Lotus&#8217; <\/a>en alg\u00fan momento, y tambi\u00e9n se sincer\u00f3 sobre lo que supon\u00eda meterse cada semana en la piel de un personaje al que, a pesar de tenerle mucho cari\u00f1o, no se parec\u00eda en nada a ella. De hecho, son tan diferentes que la distancia entre ambas obligaba a la actriz a interiorizar cada frase del di\u00e1logo para poder interpretarla con verdad.<\/p>\n<p><!-- BREAK 4 --><\/p>\n<h2>Ser aut\u00e9ntico cuesta trabajo<\/h2>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\"> <img class=\"centro_sinmarco\" height=\"1080\" width=\"1920\" loading=\"lazy\" decoding=\"async\" sizes=\"100vw\" fetchpriority=\"high\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/lisa-kudrow-sobre-sus-dificultades-actuando-en-friends-phoebe-era-tan-diferente-a-mi-que-tuve-que-justificar-todo-lo-que-decia-en-mi-cabeza-1.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/lisa-kudrow-sobre-sus-dificultades-actuando-en-friends-phoebe-era-tan-diferente-a-mi-que-tuve-que-justificar-todo-lo-que-decia-en-mi-cabeza-4.jpg 681w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/lisa-kudrow-sobre-sus-dificultades-actuando-en-friends-phoebe-era-tan-diferente-a-mi-que-tuve-que-justificar-todo-lo-que-decia-en-mi-cabeza-5.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/lisa-kudrow-sobre-sus-dificultades-actuando-en-friends-phoebe-era-tan-diferente-a-mi-que-tuve-que-justificar-todo-lo-que-decia-en-mi-cabeza-6.jpg 1366w\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/lisa-kudrow-sobre-sus-dificultades-actuando-en-friends-phoebe-era-tan-diferente-a-mi-que-tuve-que-justificar-todo-lo-que-decia-en-mi-cabeza-1.jpg\" alt=\"Phoebe en 'Friends'\"> <noscript><img alt=\"Phoebe en 'Friends'\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/lisa-kudrow-sobre-sus-dificultades-actuando-en-friends-phoebe-era-tan-diferente-a-mi-que-tuve-que-justificar-todo-lo-que-decia-en-mi-cabeza-1.jpg\"><\/noscript> <\/div>\n<\/div>\n<p>Aunque no lo parezca, <strong>Lisa Kudrow no encontraba en Phoebe una versi\u00f3n ligera de s\u00ed misma<\/strong>. En realidad era todo lo contrario y la actriz tuvo que hacer un esfuerzo para que todo lo que dec\u00eda sonara aut\u00e9ntico.<\/p>\n<p><!-- BREAK 5 --><\/p>\n<blockquote><p>\u00abPhoebe era tan diferente a m\u00ed como ser humano, que tuve que trabajarlo; necesitaba justificar todo lo que dec\u00eda en mi cabeza para que pareciera que lo dec\u00eda en serio, y que era real para ella. Era mucho trabajo.\u00bb<\/p><\/blockquote>\n<p>Kudrow reconoci\u00f3 que, a pesar de que el ambiente del rodaje era divertido y el elenco se lo pasaba bien, ella sent\u00eda<strong> la necesidad constante de racionalizar las frases de Phoebe <\/strong>para poder transmitirlas con credibilidad. Algo que incluso le gener\u00f3 inseguridades a mitad de la serie.<\/p>\n<p><!-- BREAK 6 --> <\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/actores-y-actrices\/lisa-kudrow-revela-que-ha-encontrado-nota-que-le-dejo-matthew-perry-escondida-hace-veinte-anos-tiempo-todo\" class=\"pivot-outboundlink\" data-vars-post-title=\"&quot;El momento lo es todo&quot;. Lisa Kudrow encontr\u00f3 un mensaje secreto que Matthew Perry le hab\u00eda dejado hace veinte a\u00f1os\"> <img loading=\"lazy\" alt=\"&quot;El momento lo es todo&quot;. Lisa Kudrow encontr\u00f3 un mensaje secreto que Matthew Perry le hab\u00eda dejado hace veinte a\u00f1os\" width=\"375\" height=\"142\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/lisa-kudrow-sobre-sus-dificultades-actuando-en-friends-phoebe-era-tan-diferente-a-mi-que-tuve-que-justificar-todo-lo-que-decia-en-mi-cabeza-2.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p>La exigencia que ten\u00eda Lisa Kudrow sobre s\u00ed misma lleg\u00f3 a generarle <strong>muchas dudas<\/strong> sobre su propio rendimiento como actriz, hasta el punto de llegar a pensar que no estaba a la altura de lo que el personaje requer\u00eda. Fue entonces cuando uno de sus compa\u00f1eros, <strong>Matt LeBlanc<\/strong>, le hizo ver las cosas desde otro \u00e1ngulo.<\/p>\n<p><!-- BREAK 7 --><\/p>\n<blockquote><p>\u00abRecuerdo que en la segunda o tercera temporada pens\u00e9: \u2018\u00a1Dios m\u00edo, no estoy haciendo el trabajo!\u2019. Y [Matt] LeBlanc dijo: \u2018\u00bfQu\u00e9 te pasa? Eres ella. No tienes que hacerlo\u2019.\u00bb<\/p><\/blockquote>\n<p>LeBlanc, que interpretaba a Joey, le ofreci\u00f3 una perspectiva m\u00e1s relajada que no coincid\u00eda con el enfoque meticuloso de Kudrow y que le ayud\u00f3 a verlo de otra manera. Para ella, encarnar a Phoebe implicaba mucho m\u00e1s que saberse unas l\u00edneas de di\u00e1logo graciosas. Era un ejercicio constante de empat\u00eda y coherencia. Y saber lo que hay detr\u00e1s del personaje hace que el cari\u00f1o que sentimos por \u00e9l sea incluso mayor.<\/p>\n<p><!-- BREAK 8 --><\/p>\n<p>En Espinof | <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/actores-y-actrices\/fue-devastador-lisa-kudrow-desvela-mal-que-paso-cuando-fue-despedida-frasier-como-fue-unica-hacer-audicion-director-friends\" data-vars-post-title=\"&quot;Fue devastador&quot;. Lisa Kudrow desvela lo mal que lo pas\u00f3 cuando fue despedida de 'Frasier' y c\u00f3mo fue la \u00fanica en hacer audici\u00f3n con el director de 'Friends' \" data-vars-post-url=\"https:\/\/www.espinof.com\/actores-y-actrices\/fue-devastador-lisa-kudrow-desvela-mal-que-paso-cuando-fue-despedida-frasier-como-fue-unica-hacer-audicion-director-friends\">\u00abFue devastador\u00bb. Lisa Kudrow desvela lo mal que lo pas\u00f3 cuando fue despedida de &#8216;Frasier&#8217; y c\u00f3mo fue la \u00fanica en hacer audici\u00f3n con el director de &#8216;Friends&#8217;<\/a><\/p>\n<p><!-- BREAK 9 --><\/p>\n<p>En Espinof | <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/listas\/mejores-series-2025\" data-vars-post-title=\"Las 14 mejores series de 2025 (por ahora)\" data-vars-post-url=\"https:\/\/www.espinof.com\/listas\/mejores-series-2025\">Las mejores series de 2025<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si tuvieran que escoger cu\u00e1l es su personaje preferido de &#8216;Friends&#8216;, muchos espectadores no dudar\u00edan en quedarse con Phoebe Buffay, porque es uno de los personajes m\u00e1s entra\u00f1ables, divertidos y exc\u00e9ntricos de la historia de la televisi\u00f3n. Sin embargo, para Lisa Kudrow, interpretarla durante diez temporadas no fue sencillo precisamente, por mucho que pueda parecerlo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":110676,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/110675"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=110675"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/110675\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/110676"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=110675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=110675"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=110675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}