{"id":110368,"date":"2025-07-08T15:58:36","date_gmt":"2025-07-08T15:58:36","guid":{"rendered":"http:\/\/hoycordobaweb.com\/index.php\/2025\/07\/08\/muerto-en-el-placard-el-expolicia-grasso-inquilino-del-departamento-gozo-de-domiciliaria-desde-el-2021\/"},"modified":"2025-07-08T15:58:36","modified_gmt":"2025-07-08T15:58:36","slug":"muerto-en-el-placard-el-expolicia-grasso-inquilino-del-departamento-gozo-de-domiciliaria-desde-el-2021","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/07\/08\/muerto-en-el-placard-el-expolicia-grasso-inquilino-del-departamento-gozo-de-domiciliaria-desde-el-2021\/","title":{"rendered":"Muerto en el placard: el expolic\u00eda Grasso, inquilino del departamento, goz\u00f3 de domiciliaria desde el 2021"},"content":{"rendered":"<div class=\"media_block\"><\/div>\n<div><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/muerto-en-el-placard-el-expolicia-grasso-inquilino-del-departamento-gozo-de-domiciliaria-desde-el-2021.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p><strong>Horacio Antonio Grasso<\/strong> (55), condenado en el 2009 a 27 a\u00f1os de prisi\u00f3n por homicidio en ocasi\u00f3n de robo agravado por el empleo de armas, <strong>resid\u00eda en el departamento en calle Buenos Aires 315, 3\u00b0 B,<\/strong> a pocas cuadras de la Plaza San Mart\u00edn donde se encontr\u00f3 el s\u00e1bado pasado un <strong>cad\u00e1ver maniatado dentro de un placard<\/strong>.<\/p>\n<p>Esa vivienda se convirti\u00f3 en un enigma y la rodea el horror. Grasso vivi\u00f3 all\u00ed hasta el jueves pasado, cuando el juez de Ejecuci\u00f3n Penal de C\u00f3rdoba,<strong> Facundo Moyano Centeno<\/strong>,<strong> le revoc\u00f3 la prisi\u00f3n domiciliaria.<\/strong> Ese d\u00eda ingres\u00f3 nuevamente a la c\u00e1rcel de Bouwer, donde est\u00e1 en la actualidad. <\/p>\n<p>La causa por el cuerpo encontrado est\u00e1 radicada en la Fiscal\u00eda del Distrito I Turno 5, cuya titular es Celeste Blasco; pero como este lunes comenz\u00f3 la feria invernal en los tribunales, la pesquisa qued\u00f3 a cargo del fiscal Guillermo Gonz\u00e1lez.<\/p>\n<p>Seg\u00fan los primeros indicios, el cuerpo en avanzado estado de descomposici\u00f3n ser\u00eda de una mujer. No se conoce la identidad. Mientras se procura dilucidar qui\u00e9n es y, en lo posible, c\u00f3mo hab\u00eda sido asesinada, todas las inc\u00f3gnitas se asientan en quien vivi\u00f3 all\u00ed. <\/p>\n<p class=\"destacadoNota\"><a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/cordoba\/nueva-cordoba-investigan-el-hallazgo-de-un-cadaver-en-el-placard-de-un-departamento.phtml\" rel=\"noopener noreferrer\">Nueva C\u00f3rdoba: investigan el hallazgo de un cad\u00e1ver en el placard de un departamento<\/a><\/p>\n<h2>Por qu\u00e9 Grasso gozaba de prisi\u00f3n domiciliaria<\/h2>\n<p>El expolic\u00eda tiene un derrotero de delitos, pero una sola condena que qued\u00f3 firme. Fue por el asesinato del ni\u00f1o Facundo Novillo Cancinos, en marzo del 2007. El peque\u00f1o fue la v\u00edctima fatal de un asalto y ajuste de cuentas entre los barrios Miralta y Colonia Lola del que particip\u00f3 Grasso.<\/p>\n<p>Antes hab\u00eda tenido denuncias por hechos de violencia de g\u00e9nero hacia una expareja y por tener un arsenal. Por entonces, en los albores de los 2000, hab\u00eda sido exonerado de la Polic\u00eda de C\u00f3rdoba. Pas\u00f3 de integrar la fuerza a ser miembro de pesadas bandas que mezclaban la violencia, las armas y el narcotr\u00e1fico. Con ese perfil fue <strong>condenado en el a\u00f1o 2009 por la C\u00e1mara 3a del Crimen<\/strong>.<\/p>\n<p>PERFIL C\u00d3RDOBA pudo reconstruir el derrotero de su detenci\u00f3n.<\/p>\n<p>Horacio Antonio Grasso cumpl\u00eda la pena en el complejo penitenciario de R\u00edo Cuarto. <\/p>\n<p>El <strong>31 de enero del 2019<\/strong>, el juez de Ejecuci\u00f3n Penal de esa ciudad, de turno durante la feria, le concedi\u00f3 la <strong>prisi\u00f3n domiciliaria <\/strong>por razones de salud. Este medio no pudo precisar cu\u00e1l es la patolog\u00eda por la cual le dieron el beneficio. Si bien ten\u00eda padecimientos de arritmia y diabetes tipo 2, artrosis reumatoidea, no se registran datos sobre cuadros agudos que podr\u00edan haberla justificado. <\/p>\n<p>Quien se hizo responsable de Grasso en esa oportunidad fue su madre, Eunice Meyer. La mujer, sin embargo, result\u00f3 v\u00edctima de fuertes agresiones por parte del hijo.<\/p>\n<p>El<strong> 6 de abril del a\u00f1o 2020, <\/strong>el juez de Ejecuci\u00f3n Penal del 1\u00b0 turno de la ciudad de C\u00f3rdoba, Facundo Moyano Centeno, <strong>le revoc\u00f3 la domiciliaria<\/strong> y dispuso que sea alojado en el Centro Psicoasistencial por un cuadro psicol\u00f3gico complejo.<\/p>\n<p>Un mes despu\u00e9s, el 6 de mayo del 2020, lo trasladaron al penal de R\u00edo Cuarto. <\/p>\n<p>El <strong>5 de marzo del 2021<\/strong>, el juez de Ejecuci\u00f3n de esa ciudad <strong>Gustavo Jos\u00e9 Echenique Esteve nuevamente le permiti\u00f3 la prisi\u00f3n domiciliaria,<\/strong> con tobillera electr\u00f3nica.<strong> Fij\u00f3 domicilio en el departamento del horror, Buenos Aires 315, 3\u00b0 B,<\/strong> ciudad de C\u00f3rdoba. Por esa raz\u00f3n, desde entonces qued\u00f3 bajo el control del juez cordob\u00e9s Moyano Centeno. <\/p>\n<p>El <strong>3 de julio pasado<\/strong>, a <strong>m\u00e1s de cuatro a\u00f1o<\/strong>s, el magistrado le revoc\u00f3 la prisi\u00f3n domiciliaria y<strong> <\/strong>o<strong>rden\u00f3 su inmediata detenci\u00f3n.<\/strong> <\/p>\n<p>Los encargados del control de Grasso eran el <strong>Patronato del Liberado<\/strong> y el <a target=\"_blank\" href=\"https:\/\/www.cba.gov.ar\/quedo-inaugurado-el-centro-de-control-de-personas-bajo-vigilancia-electronica\/\" rel=\"noopener noreferrer\">Centro de Control de Personas Bajo Vigilancia Electr\u00f3nica<\/a> (Ccpve), que dependen del Servicio Penitenciario.<\/p>\n<p><strong>Los informes no eran positivos<\/strong>. El interrogante que subyace es por qu\u00e9 pas\u00f3 tanto tiempo, m\u00e1s de cuatro a\u00f1os, sin que fuera enviado nuevamente a la c\u00e1rcel. <\/p>\n<p>La data de la muerte del cuerpo hallado en el placard <strong>coincide, en apariencia, con la amplia ventana temporal de su prisi\u00f3n domiciliaria<\/strong>.<\/p>\n<p class=\"destacadoNota\"><a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/cordoba\/pidieron-sobreseimiento-y-libertad-a-oscar-gonzalez-el-argumento-juridico-de-la-defensa.phtml\" rel=\"noopener noreferrer\">Pidieron sobreseimiento y libertad a Oscar Gonz\u00e1lez: el argumento jur\u00eddico de la defensa<\/a><\/p>\n<h2>Intent\u00f3 la libertad condicional, pero la rechazaron<\/h2>\n<p>De haber tenido una conducta intachable en la c\u00e1rcel, Horacio Grasso podr\u00eda haber obtenido la libertad condicional. La condena total se hab\u00eda fijado para el <strong>24 de abril del 2034. <\/strong>Pero el C\u00f3digo Penal y la Ley de Ejecuci\u00f3n Penal establecen un proceso de morigeraci\u00f3n de encierro y una salida gradual para la resocializaci\u00f3n de las personas condenadas. El <strong>24 de abril pasado estaba en condiciones de pedirla. <\/strong><\/p>\n<p>Sin embargo, <strong>el 24 de junio el pedido fue rechazado<\/strong>. Incluso lleg\u00f3 en casaci\u00f3n al TSJ que no le concedi\u00f3 la ansiada libertad condicional.<\/p>\n<p>Ese mes, su tutor &#8211; C.D.R. renunci\u00f3 a esa responsabilidad y comunic\u00f3 al juez que Grasso porque <strong>no hac\u00eda caso a las restricciones que le hab\u00edan impuesto. <\/strong><\/p>\n<p class=\"destacadoNota\"><a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/cordoba\/oscar-gonzalez-con-tobillera-electronica-pidieron-ampliar-el-perimetro-de-su-detencion-domiciliaria.phtml\" rel=\"noopener noreferrer\">Oscar Gonz\u00e1lez con tobillera electr\u00f3nica: pidieron ampliar el per\u00edmetro de su detenci\u00f3n domiciliaria<\/a><\/p>\n<h2>Investigan si adulter\u00f3 un certificado m\u00e9dico<\/h2>\n<p>Bajo la lupa en todo su derrotero, ahora investigan si Horacio Antonio Grasso <strong>tambi\u00e9n falsific\u00f3 un certificado m\u00e9dico.<\/strong> <\/p>\n<p>En los tr\u00e1mites previos al pedido de libertad condicional, present\u00f3 un informe firmado por F.C. con un n\u00famero de matr\u00edcula profesional. Cuando la Justicia consult\u00f3 en la p\u00e1gina del Consejo de M\u00e9dicos de la Provincia de C\u00f3rdoba, encontraron que <strong>esa identificaci\u00f3n pertenece a una m\u00e9dica, que nada tiene que ver con el nombre inscripto en el documento.<\/strong> Por esa raz\u00f3n, se remitieron antecedentes para averiguar el episodio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Horacio Antonio Grasso (55), condenado en el 2009 a 27 a\u00f1os de prisi\u00f3n por homicidio en ocasi\u00f3n de robo agravado por el empleo de armas, resid\u00eda en el departamento en calle Buenos Aires 315, 3\u00b0 B, a pocas cuadras de la Plaza San Mart\u00edn donde se encontr\u00f3 el s\u00e1bado pasado un cad\u00e1ver maniatado dentro de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":110369,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[1562,41,1558,1559,1557,328,1563,1561,1560],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/110368"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=110368"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/110368\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/110369"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=110368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=110368"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=110368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}