{"id":104615,"date":"2025-05-10T09:00:04","date_gmt":"2025-05-10T09:00:04","guid":{"rendered":"https:\/\/www.trendencias.com\/opinion\/soy-sevillana-tengo-suerte-que-nadie-mi-ciudad-clasista-se-nota-reglas-como-vestir-feria-abril"},"modified":"2025-05-10T09:00:04","modified_gmt":"2025-05-10T09:00:04","slug":"soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/05\/10\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril\/","title":{"rendered":"Soy sevillana y tengo m\u00e1s suerte que nadie, pero mi ciudad es clasista. Se nota en las reglas de c\u00f3mo vestir en la Feria de abril"},"content":{"rendered":"<p>No, no creas que este titular, el comienzo del mismo, nace desde la soberbia, por lo menos no desde la m\u00eda. Es un fragmento de la sevillana <em>Sevillan\u00eda<\/em> de Los del R\u00edo. Y es que a nosotros no nos hace falta abuela, qu\u00e9 te digo. No me gusta negar lo innegable, me gusta afrontarlo y gestionarlo como mejor pueda.<\/p>\n<p><!-- BREAK 1 --> <\/p>\n<p>Seguro que has le\u00eddo u o\u00eddo en alguna ocasi\u00f3n <strong>una frase muy manida de Antonio Gala<\/strong>, cordob\u00e9s, que dice as\u00ed \u00abLo malo no es que los sevillanos piensen que tienen la ciudad m\u00e1s bonita del mundo; lo peor es que puede que tengan hasta raz\u00f3n\u00bb. Y madre m\u00eda, c\u00f3mo lo tenemos grabado a fuego, \u00bfeh? De hecho, no me considero una persona demasiado parcial, pero hace unas semanas estaba discutiendo, casi porfiando, con un amigo qu\u00e9 alc\u00e1zares eran m\u00e1s bonitos, si los de Sevilla o los de C\u00f3rdoba. Y sin haber visitado los segundos estoy segura de que la respuesta est\u00e1 en los primeros. Y as\u00ed se lo dije varias veces.<\/p>\n<p><!-- BREAK 2 --><\/p>\n<p>\u00bfEstoy ech\u00e1ndome tierra encima con este inicio antes de siquiera ponerme verborreica con lo que de verdad me concierne hoy? No, que va, solo te estoy dejando ver una parte de m\u00ed para que comprendas que a pesar de que me encanta mi ciudad, aunque yo soy de un pueblo, puedo ver <strong>sus luces, que son muchas, y sus sombras<\/strong>, que en ocasiones logran encapotar el m\u00e1s azul de los cielos, el mismo que recordaba Antonio Machado en ese trocito de papel que encontraron en el bolsillo del abrigo que llevaba puesto cuando falleci\u00f3 en el exilio en Colliure, Francia.<\/p>\n<p><!-- BREAK 3 --> <\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\">\n<div class=\"caption-img \"> <img class=\"centro_sinmarco\" height=\"1821\" width=\"1024\" loading=\"lazy\" decoding=\"async\" sizes=\"100vw\" fetchpriority=\"high\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-7.jpg 681w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-8.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-9.jpg 1366w\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril.jpg\" alt=\"Feria de abril pol\u00e9mica\"> <noscript><img alt=\"Feria de abril pol\u00e9mica\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril.jpg\"><\/noscript> <span>El d\u00eda del Pesca\u00edto de la Feria de Abril, que fue en mayo, de 2019.<\/span> <\/div><\/div>\n<\/div>\n<h2>La carta de presentaci\u00f3n: Sevilla, una ciudad para algunos sevillanos, al igual que su Feria<\/h2>\n<p>Puedes ser dos tipos de sevillano: de bien o de mal. Y es que a pesar de que la vida se mueve en una escala de grises, Sevilla ve en blanco y negro: Sevilla o Betis, Triana o Sevilla, serranito o piripi, Esperanza o Macarena&#8230; Y as\u00ed un largo etc\u00e9tera que olvida todo lo que rodea a lo que siempre salta a la vista. Tenemos que ser conscientes de lo mucho que aportan ciertos s\u00edmbolos de la ciudad, pero tambi\u00e9n hay que saber que, sin el resto, estos no se sostienen. Est\u00e1 genial disfrutar del centro hist\u00f3rico, pero los barrios de la periferia tambi\u00e9n son la vida de la ciudad y soportan muchas de las grandes casas que engalanan las calles m\u00e1s visitadas.<\/p>\n<p><!-- BREAK 4 --><\/p>\n<p>Aunque bueno, casas, casas cada vez quedan menos con esto de <strong>la gentrificaci\u00f3n<\/strong>, porque a ver qui\u00e9n soporta semejantes <a class=\"text-outboundlink\" href=\"https:\/\/www.trendencias.com\/general\/hemos-probado-simulador-alquiler-que-te-dice-precio-maximo-para-alquilar-ahora-nos-da-miedo-que-usen-nuestros-caseros\" data-vars-post-title=\"Hemos probado la calculadora de alquiler que te dice el precio m\u00e1ximo para alquilar una vivienda y nos da miedo que lo usen nuestros caseros\" data-vars-post-url=\"https:\/\/www.trendencias.com\/general\/hemos-probado-simulador-alquiler-que-te-dice-precio-maximo-para-alquilar-ahora-nos-da-miedo-que-usen-nuestros-caseros\">precios de los alquileres<\/a> con la proliferaci\u00f3n de los pisos y apartamentos tipo AirBnB totalmente descontrolados. Pero bueno, luego <a class=\"text-outboundlink\" href=\"https:\/\/www.xataka.com\/magnet\/sevilla-quiere-cobrar-a-no-residentes-acceder-a-plaza-espana-cuestion-ue-considera-legal\" data-vars-post-title=\"Sevilla quiere cobrar a los no residentes por acceder a la Plaza de Espa\u00f1a. La cuesti\u00f3n es si la UE lo considera legal\" data-vars-post-url=\"https:\/\/www.xataka.com\/magnet\/sevilla-quiere-cobrar-a-no-residentes-acceder-a-plaza-espana-cuestion-ue-considera-legal\">ponemos el acceso a la Plaza de Espa\u00f1a de pago<\/a> y ya estar\u00eda, \u00bfno?<\/p>\n<p><!-- BREAK 5 --><\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\"> <img class=\"centro_sinmarco\" height=\"853\" width=\"1280\" loading=\"lazy\" decoding=\"async\" sizes=\"100vw\" fetchpriority=\"high\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-1.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-10.jpg 681w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-11.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-12.jpg 1366w\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-1.jpg\" alt=\"Sevilla\"> <noscript><img alt=\"Sevilla\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-1.jpg\"><\/noscript> <\/div>\n<\/div>\n<p>Por cierto, la Sevilla en blanco y negro es la misma que no consigui\u00f3 procesar la propuesta del <a class=\"text-outboundlink\" href=\"https:\/\/www.trendencias.com\/opinion\/soy-sevillana-vivo-semana-santa-se-muy-bien-donde-nacen-todas-criticas-al-polemico-cartel\" data-vars-post-title=\"Soy sevillana, vivo la Semana Santa y s\u00e9 muy bien de d\u00f3nde nacen todas las cr\u00edticas al pol\u00e9mico cartel\" data-vars-post-url=\"https:\/\/www.trendencias.com\/opinion\/soy-sevillana-vivo-semana-santa-se-muy-bien-donde-nacen-todas-criticas-al-polemico-cartel\">\u00abpol\u00e9mico\u00bb cartel de la pasada Semana Santa del artista Salustiano Garc\u00eda<\/a>. Es la misma ciudad a la que le encanta ser elitista y endog\u00e1mica, lo lleva en su ADN junto a lo de estrenar ropa el Domingo de Ramos. \u00a1Y ay! C\u00f3mo se mueren algunos por ir escalando de estrato en estrato y pisoteando a todo lo que se encuentran a su paso. Porque claro, as\u00ed es m\u00e1s satisfactorio, \u00bfno?<\/p>\n<p><!-- BREAK 6 --> <\/p>\n<p>Pues con la Feria sucede lo mismo. No, no entres a compararla con la de C\u00f3rdoba, Jerez o El Puerto. No merece la pena. Esta fiesta es <strong>una representaci\u00f3n m\u00e1s de la idiosincrasia de una ciudad <\/strong>de lo m\u00e1s peculiar, algo que tambi\u00e9n se traduce en el c\u00f3digo de vestimenta exigido a medias para participar de ella.<\/p>\n<p><!-- BREAK 7 --><\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\">\n<div class=\"caption-img \"> <img class=\"centro_sinmarco\" height=\"2162\" width=\"1200\" loading=\"lazy\" decoding=\"async\" sizes=\"100vw\" fetchpriority=\"high\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-2.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-13.jpg 681w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-14.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-15.jpg 1366w\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-2.jpg\" alt=\"Feria de abril pol\u00e9mica\"> <noscript><img alt=\"Feria de abril pol\u00e9mica\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-2.jpg\"><\/noscript> <span>Ech\u00e1ndome unas risitas con este \u00e1rbol tan gracioso en el Real en 2019.<\/span> <\/div><\/div>\n<\/div>\n<h2>El c\u00f3digo de vestimenta de la Feria en unos sencillos pasos: haz lo que yo te diga<\/h2>\n<p>No, querida, por mucho que hayas visto estos d\u00edas, estas pasadas semanas, en redes sociales, <strong>no es necesario que vayas a la Feria vestida de flamenca<\/strong> ni que saques del guardapolvos tu traje de la confirmaci\u00f3n para hacer acto de presencia en el Real.<\/p>\n<p><!-- BREAK 8 --><\/p>\n<p>De verdad, no hay ning\u00fan segurata de la moda en la portada que te vaya a dar el carn\u00e9 de aprobado o suspendido por llevar traje, chinos y camisa o unas Total 90. Pero te mentir\u00eda si te dijera que en <strong>el <\/strong><em><strong>dress code<\/strong><\/em><strong> de la Feria de Sevilla<\/strong> no est\u00e1 todo escrito. Y mira, a m\u00ed me encanta ver a un hombre con traje, si es cruzado, m\u00e1s, pero oye, que un pantal\u00f3n de ch\u00e1ndal gris tambi\u00e9n tiene su aquel (gui\u00f1o, gui\u00f1o, codazo, codazo).<\/p>\n<p><!-- BREAK 9 --><\/p>\n<p>Venga, ahora en serio. Seguro que has escuchado por mil y una v\u00edas que para pisar albero tienes que llevar, si eres chico y encajas en los est\u00e1ndares que tradicionalmente se asocian al g\u00e9nero masculino, un traje de chaqueta. Y esto es verdad a medias.<\/p>\n<p><!-- BREAK 10 --> <\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\"> <img class=\"centro_sinmarco\" height=\"1800\" width=\"2400\" loading=\"lazy\" decoding=\"async\" sizes=\"100vw\" fetchpriority=\"high\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-3.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-16.jpg 681w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-17.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-18.jpg 1366w\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-3.jpg\" alt=\"Feria de abril\"> <noscript><img alt=\"Feria de abril\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-3.jpg\"><\/noscript> <\/div>\n<\/div>\n<p>Como puede que sepas, en Sevilla la mayor\u00eda de casetas son privadas, por lo que cada una <strong>se guarda el derecho de admisi\u00f3n<\/strong>, como en las discotecas o ciertos restaurantes. Y s\u00ed, hay algunas en las que ni siquiera te dejan entrar si no llevas americana, haga 25 grados o 40. Ten claro cristalino que si no la tienes te vas a llevar muchas miradas por encima del hombro. Digamos que no se trata de una norma oficial pero s\u00ed oficiosa. Y una vez m\u00e1s el problema no est\u00e1 en la ropa que decidas llevar, sino en el ojo del que mira.<\/p>\n<p><!-- BREAK 11 --><\/p>\n<p>En estos d\u00edas hemos visto varios v\u00eddeos que se han popularizado bastante en redes sociales y que han resultado pol\u00e9micos. El primero es de una sastrer\u00eda, Bund Company. Un chico aparece dando una serie de <em>tips<\/em> sobre c\u00f3mo acudir vestido a la Feria. Un contenido que refleja muy bien las expectativas de estilo para los chicos, con la acepci\u00f3n que antes he comentado, en la Feria de Sevilla.<\/p>\n<p><!-- BREAK 12 --><\/p>\n<blockquote class=\"tiktok-embed\" cite=\"https:\/\/www.tiktok.com\/@bund_company\/video\/7357293754363039008\" data-video-id=\"7357293754363039008\" data-embed-from=\"oembed\" readability=\"6.5687086092715\">\n<section readability=\"7.8824503311258\"> <a target=\"_blank\" title=\"@bund_company\" href=\"https:\/\/www.tiktok.com\/@bund_company?refer=embed\" rel=\"noopener noreferrer\">@bund_company<\/a> <\/p>\n<p>5 TIPS PARA NO FALLAR VISTIENDO EN FERIA \ud83d\udc83\ud83c\udffc Despu\u00e9s de lo que os ha gustado el v\u00eddeo de ayer no pod\u00edamos no ponerle la guinda al pastel con 5 detalles fundamentales a la hora de vestir en la feria \u00a1VAMOS! \ud83d\udd25 Desde no usar gafas de sol (Si, por mucho que te deslumbres, no las uses) a qu\u00e9 tipo de zapato debes usar, la importancia de los complementos, y hasta de los calcetines! Si cuidas todos estos detalles no te faltar\u00e1 nada para ser el mejor vestido \ud83d\ude0e Y para ti cu\u00e1l es el detalle m\u00e1s importante? \ud83e\udd2f <a title=\"aprendeentiktok\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/aprendeentiktok?refer=embed\" rel=\"noopener noreferrer\">#aprendeentiktok<\/a> <a title=\"fashion\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/fashion?refer=embed\" rel=\"noopener noreferrer\">#fashion<\/a> <a title=\"modaentiktok\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/modaentiktok?refer=embed\" rel=\"noopener noreferrer\">#ModaEnTikTok<\/a><\/p>\n<p> <a target=\"_blank\" title=\"\u266c original sound - bund\" href=\"https:\/\/www.tiktok.com\/music\/original-sound-7357293796164422432?refer=embed\" rel=\"noopener noreferrer\">\u266c original sound &#8211; bund<\/a> <\/section>\n<\/blockquote>\n<p>Ha habido muchos comentarios negativos a ra\u00edz de esta publicaci\u00f3n, especialmente en X. Sin embargo, no pienso que se trate del <em>post <\/em>m\u00e1s candente. Lo que personalmente me fastidia, por experiencia, es lo mucho que se mira lo que llevamos y <a class=\"text-outboundlink\" href=\"https:\/\/www.xataka.com\/magnet\/feria-abril-ha-servido-durante-anos-gente-grabe-a-personas-borrachas-hay-problema-multas\" data-vars-post-title=\"Grabar a gente borracha en la Feria de Abril se ha convertido en una tradici\u00f3n. Las multas por hacerlo no son tan divertidas\" data-vars-post-url=\"https:\/\/www.xataka.com\/magnet\/feria-abril-ha-servido-durante-anos-gente-grabe-a-personas-borrachas-hay-problema-multas\">lo poco que importa c\u00f3mo nos comportemos luego en la Feria<\/a>.<\/p>\n<p><!-- BREAK 13 --><\/p>\n<p>Te puedo decir que me he llevado yendo durante muchos, muchos a\u00f1os, a una de las casetas con socios con m\u00e1s poder adquisitivo de todo el Real y no sabes todo lo que se ve all\u00ed. Mi parte favorita era observar a gente que deb\u00eda mucho dinero con vestidos de 400 euros (no trajes de flamenca, vestidos), bolsos de 1200 y sandalias de 800. Y es que al fin y al cabo <strong>hay cosas que nunca comprar\u00e1n los billetes<\/strong>.<\/p>\n<p><!-- BREAK 14 --><\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\">\n<div class=\"caption-img \"> <img class=\"centro_sinmarco\" height=\"1024\" width=\"768\" loading=\"lazy\" decoding=\"async\" sizes=\"100vw\" fetchpriority=\"high\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-4.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-19.jpg 681w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-20.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-21.jpg 1366w\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-4.jpg\" alt=\"FEria de abril pol\u00e9mica\"> <noscript><img alt=\"FEria de abril pol\u00e9mica\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-4.jpg\"><\/noscript> <span>Domingo de Feria de 2023. Top de Zara comprado en rebajas por 5,99 euros, una falda del outlet de Pedro del Hierro de 19,99 euros, sandalias de Miu Miu de segunda mano compradas en Vestiare Collective por 45 euros y pendientes de Marucca.<\/span> <\/div><\/div>\n<\/div>\n<p>No obstante, el v\u00eddeo que me ha puesto la piel de gallina y que me ha generado mucha violencia ha sido uno que ha publicado la usuaria de TikTok @elenita.la.fantastica, cuya cuenta parece haber desaparecido de la faz de la plataforma.<\/p>\n<p><!-- BREAK 15 --> <\/p>\n<p>En el mismo, una chica bastante joven se dedicaba a grabar sin permiso a muchas flamencas de las que estaban a su alrededor, <strong>critic\u00e1ndolas con comentarios muy hirientes sobre los dise\u00f1os que estas luc\u00edan<\/strong>. Y lo m\u00e1s gracioso es que ella sale con un pendiente menos, la flor doblada, muy despeinada y con un mantoncillo que no se atiene nada a esos est\u00e1ndares est\u00e9ticos que marca la Feria de Sevilla.<\/p>\n<p><!-- BREAK 16 --><\/p>\n<p>Si hay algo que representa <strong>el traje de flamenca es la diversidad<\/strong>, el color, el trabajo de lo hecho a medida y la posibilidad de personalizar cada creaci\u00f3n. Puede gustarte m\u00e1s o menos, pero en qu\u00e9 momento olvidamos algo tan b\u00e1sico como el hecho de que todo el mundo puede vestir como le plazca. Eso s\u00ed, est\u00e1 claro que el term\u00f3metro de la sevillan\u00eda no funciona a gusto de todos.<\/p>\n<p><!-- BREAK 17 --><\/p>\n<h2>La Feria no es <em>engagement<\/em><\/h2>\n<p>Esta frase la vimos en su momento en el Instagram de la <em>influencer <\/em>y dise\u00f1adora <a rel=\"noopener, noreferrer\" href=\"https:\/\/www.instagram.com\/rocioosorno\/\">Roc\u00edo Osorno<\/a>. Y es que la Feria de Sevilla y los sevillanos, nuestras tradiciones, nos hemos convertido en <strong>una especie de parque tur\u00edstico<\/strong> del que todos pueden picotear a su antojo. Eso s\u00ed, lo de imponer una tasa tur\u00edstica para las estancias en alojamientos lo dejamos para otro d\u00eda.<\/p>\n<p><!-- BREAK 18 --><\/p>\n<p>Puede que el orgullo de ser andaluces lo hayamos forjado a base de golpes y que a\u00fan no hayamos aprendido despu\u00e9s de haber sido los art\u00edfices de la riqueza de otras comunidades que tanto sobresalen y que tantos golpes en el pecho se dan. Esas que podr\u00edan personificar la frase m\u00e1s capitalista de la historia de \u00abser un hombre hecho a s\u00ed mismo\u00bb.<\/p>\n<p><!-- BREAK 19 --><\/p>\n<p>Siempre hemos sido los proveedores: de tierra, de buen tiempo, de mano de obra. Y ahora tambi\u00e9n somos el patio de recreo de <strong>los que tantas veces nos han menospreciado por un acento<\/strong>, por unas tradiciones y una forma de ver la vida que no es mejor, ni peor, simplemente diferente.<\/p>\n<p><!-- BREAK 20 --><\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\"> <img class=\"centro_sinmarco\" height=\"847\" width=\"1066\" loading=\"lazy\" decoding=\"async\" sizes=\"100vw\" fetchpriority=\"high\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-5.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-22.jpg 681w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-23.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-24.jpg 1366w\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-5.jpg\" alt=\"Feria de abril\"> <noscript><img alt=\"Feria de abril\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/05\/soy-sevillana-y-tengo-mas-suerte-que-nadie-pero-mi-ciudad-es-clasista-se-nota-en-las-reglas-de-como-vestir-en-la-feria-de-abril-5.jpg\"><\/noscript> <\/div>\n<\/div>\n<p>Cuando llega la primavera, desde el resto de Espa\u00f1a comienza el descenso de hordas de <em>wannabes <\/em>que claman al cielo diciendo que uno de sus bisabuelos naci\u00f3 dentro de nuestros fronteras. De esos que si nos despistamos comienzan a sesear o a cecear, al gusto, seg\u00fan convenga. Y que te sueltan un \u00abqu\u00e9 gracioso hablas\u00bb.<\/p>\n<p><!-- BREAK 21 --> <\/p>\n<p>Los mismos que en verano han conseguido que un alquiler en El Puerto de Santa Mar\u00eda se dispare a precio capitalino de barrio pijo, se manchan sus brillantes zapatos en el Real, mimetiz\u00e1ndose, pretendi\u00e9ndolo, con el resto de asistentes a la Feria. Y s\u00ed, si van \u00abbien vestidos\u00bb, lo mismo el sevillan\u00f3metro los quiere un pel\u00edn m\u00e1s que a un aut\u00e9ntico sevillano de El Cerro del \u00c1guila.<\/p>\n<p><!-- BREAK 22 --><\/p>\n<p>Pero tranquila, que al igual que el brillo de los ojos no se opera, <strong>el andalucismo no se compra<\/strong>.<\/p>\n<p>Fotos | Cristina Sobrino Calado (<a rel=\"noopener, noreferrer\" href=\"https:\/\/www.instagram.com\/cristinasobrinoc\/\" data-id=\"noopener, noreferrer\">@cristinasobrinoc<\/a>), <a rel=\"noopener, noreferrer\" href=\"https:\/\/pixabay.com\/es\/users\/alpcem-13834806\/?utm_source=link-attribution&amp;utm_medium=referral&amp;utm_campaign=image&amp;utm_content=5164368\">Alp Cem<\/a> en <a rel=\"noopener, noreferrer\" href=\"https:\/\/pixabay.com\/es\/\/?utm_source=link-attribution&amp;utm_medium=referral&amp;utm_campaign=image&amp;utm_content=5164368\">Pixabay<\/a>, <a rel=\"noopener, noreferrer\" href=\"https:\/\/www.flickr.com\/photos\/victoriapeckham\/8713078917\">victoriapeckham en Flickr<\/a>, <a rel=\"noopener, noreferrer\" href=\"https:\/\/www.flickr.com\/photos\/54214210@N04\/19062525063\/\">Sevilla Congress &amp; Convention Bureau<\/a> en Flickr<\/p>\n<p>En Trendencias | <a href=\"https:\/\/www.trendencias.com\/propuestas-y-consejos\/21-vestidos-invitada-boda-colores-precio-zara-mango-asos-corte-ingles-h-m%C3%A7\">49 vestidos de invitada de boda por colores y precio de Zara, Mango, Asos, El Corte Ingl\u00e9s, H&amp;M y m\u00e1s<\/a><\/p>\n<p>En Trendencias | <a class=\"text-outboundlink\" href=\"https:\/\/www.trendencias.com\/gourmet\/23-aperitivos-faciles-rapidos-para-tus-proximas-sonadas-reuniones-familia-amigos\" data-vars-post-title=\"25 aperitivos f\u00e1ciles y r\u00e1pidos para tus reuniones con familia y amigos\" data-vars-post-url=\"https:\/\/www.trendencias.com\/gourmet\/23-aperitivos-faciles-rapidos-para-tus-proximas-sonadas-reuniones-familia-amigos\">29 aperitivos f\u00e1ciles y r\u00e1pidos para tus pr\u00f3ximas y so\u00f1adas reuniones con familia y amigos<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No, no creas que este titular, el comienzo del mismo, nace desde la soberbia, por lo menos no desde la m\u00eda. Es un fragmento de la sevillana Sevillan\u00eda de Los del R\u00edo. Y es que a nosotros no nos hace falta abuela, qu\u00e9 te digo. No me gusta negar lo innegable, me gusta afrontarlo y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":104616,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/104615"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=104615"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/104615\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/104616"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=104615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=104615"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=104615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}