{"id":100468,"date":"2025-03-27T05:50:00","date_gmt":"2025-03-27T05:50:00","guid":{"rendered":"http:\/\/hoycordobaweb.com\/index.php\/2025\/03\/27\/caso-loan-confirmaron-los-procesamientos-contra-los-diez-acusados-en-la-causa-paralela\/"},"modified":"2025-03-27T05:50:00","modified_gmt":"2025-03-27T05:50:00","slug":"caso-loan-confirmaron-los-procesamientos-contra-los-diez-acusados-en-la-causa-paralela","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/03\/27\/caso-loan-confirmaron-los-procesamientos-contra-los-diez-acusados-en-la-causa-paralela\/","title":{"rendered":"Caso Loan: confirmaron los procesamientos contra los diez acusados en la causa paralela"},"content":{"rendered":"<div class=\"media_block\"><\/div>\n<p>La C\u00e1mara Federal de <a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/policia\/loan-nuevas-medidas-y-un-testimonio-explosivo.phtml\" rel=\"noopener noreferrer\">Corrientes<\/a> ratific\u00f3 este mi\u00e9rcoles 26 de marzo el <strong>procesamiento de los diez acusados de entorpecer la causa <\/strong>que investiga la presunta sustracci\u00f3n y ocultamiento de <a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/sociedad\/caso-loan-un-analisis-de-adn-descarto-que-sofia-herrera-sea-la-hija-adoptiva-del-matrimonio-perez-y-caillava.phtml\" rel=\"noopener noreferrer\">Loan Danilo Pe\u00f1a<\/a>, quienes <strong>se presentaban como integrantes de la <a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/judiciales\/caso-lucio-dupuy-separaron-de-celda-a-la-madre-y-su-pareja-por-pedido-de-la-familia.phtml\" rel=\"noopener noreferrer\">Fundaci\u00f3n Dupuy<\/a><\/strong>, sin estar vinculados de manera oficial a la organizaci\u00f3n pampeana ni contar con las habilitaciones profesionales que aseguraban tener. <\/p>\n<p>Se trata de Elizabeth Noem\u00ed Cutaia, Alan Juan Jos\u00e9 Ca\u00f1ete, Delfina Taborda, Leonardo Daniel Rubio, Ver\u00f3nica Paola Machuca Yuni, Pablo Javier Noguera, Pablo Gabriel N\u00fa\u00f1ez, Valeria Liliana L\u00f3pez, Nicol\u00e1s Gabriel Soria y Esteban Federico Rossi Colombo, quienes est\u00e1n <strong>acusados de privaci\u00f3n ileg\u00edtima de la libertad, encubrimiento, estafa calificada en perjuicio de la administraci\u00f3n p\u00fablica y usurpaci\u00f3n de t\u00edtulos<\/strong>, entre otras figuras penales.<\/p>\n<p>En di\u00e1logo con la agencia <em>Noticias Argentinas<\/em>, el abogado querellante Juan Pablo Gallego defini\u00f3 este fallo como <strong>\u201cun fuerte espaldarazo a su trabajo y al de la jueza Cristina Pozzer Penzo\u201d<\/strong>.<\/p>\n<div class=\"subscription\" readability=\"6.683257918552\">\n<p> Esto no les gusta a los autoritarios <\/p>\n<div class=\"subscription__container\" readability=\"6.1467391304348\">\n<div class=\"subscription__text-wrapper\" readability=\"31.20652173913\">\n<p> El ejercicio del periodismo profesional y cr\u00edtico es un pilar fundamental de la democracia. Por eso molesta a quienes creen ser los due\u00f1os de la verdad. <\/p>\n<\/p><\/div><\/div><\/div>\n<p>Seg\u00fan la investigaci\u00f3n, los acusados habr\u00edan llevado adelante diferentes maniobras para encubrir los hechos relacionados con la desaparici\u00f3n del menor. De acuerdo a los informes judiciales, <strong>el grupo habr\u00eda trasladado a Camila N\u00fa\u00f1ez, Macarena Pe\u00f1a y varios menores de edad <\/strong>a un hotel<strong> <\/strong>denominado \u201cDespertar del Iber\u00e1\u201d, donde habr\u00edan <strong>restringido su libertad y manipulado sus declaraciones <\/strong>para entorpecer la investigaci\u00f3n judicial.<\/p>\n<p>Estas acciones se habr\u00edan desarrollado <strong>durante diez d\u00edas, alegando un programa de contenci\u00f3n que no contaba con ninguna autorizaci\u00f3n oficial<\/strong>. Seg\u00fan el fallo, los imputados \u201caprovecharon la vulnerabilidad de las v\u00edctimas\u201d, \u201cmanipularon sus testimonios\u201d, \u201cafectaron su capacidad de autodeterminaci\u00f3n\u201d y \u201cel consentimiento estaba viciado\u201d.<\/p>\n<p>\u201cAunque cada uno de los imputados realiz\u00f3 diferentes actos de manera individual (traslado de las personas al hotel Despertar del Iber\u00e1, manipulaci\u00f3n de los testimonios, control de las entrevistas, reconstrucci\u00f3n del hecho, entre otros), <strong>todos, en conjunto, contribuyeron a desviar la investigaci\u00f3n, obstaculizando la posibilidad de que la Justicia identificara adecuadamente a los responsables<\/strong> de la desaparici\u00f3n del menor\u00bb, expresaron los camaristas en su dictamen.<\/p>\n<div>\n<figure class=\"image\"><picture><source media=\"(max-width: 440px)\" srcset=\"https:\/\/fotos.perfil.com\/\/2024\/08\/08\/440\/0\/loan-pena-esta-desaparecido-hace-55-dias-1850311.jpeg?webp\"><source media=\"(max-width: 1019px)\" srcset=\"https:\/\/fotos.perfil.com\/\/2024\/08\/08\/712\/0\/loan-pena-esta-desaparecido-hace-55-dias-1850311.jpeg?webp\"><img alt=\"Loan Pe\u00f1a, est\u00e1 desaparecido hace 55 d\u00edas.\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/caso-loan-confirmaron-los-procesamientos-contra-los-diez-acusados-en-la-causa-paralela.jpg\" loading=\"lazy\"><\/picture><figcaption>Loan Pe\u00f1a desapareci\u00f3 el 13 de junio de 2024 en Corrientes<\/figcaption><\/figure>\n<\/p><\/div>\n<p>\u00abEn tal sentido, se advierte nuevamente que, pese a que no todos llevaron a cabo la totalidad de estos comportamientos, contribuyeron de forma esencial, a partir de la realizaci\u00f3n de su aporte correspondiente, a la comisi\u00f3n del delito\u201d, a\u00f1adieron. <strong>El m\u00f3vil habr\u00eda sido econ\u00f3mico<\/strong>: el grupo habr\u00eda usado como fachada la \u201cFundaci\u00f3n Dupuy\u201d para <strong>obtener pagos del municipio de 9 de Julio por $1.800.000 <\/strong>en concepto de honorarios por sus servicios.<\/p>\n<p>Tras analizar todas las pruebas, la C\u00e1mara aval\u00f3 lo resuelto por la jueza Pozzer Penzo, pero introdujo<strong> modificaciones favorables para las defensas de Rubio y Taborda<\/strong>, al considerar que no se encontraban en la localidad donde ocurrieron los hechos relacionados con la privaci\u00f3n ileg\u00edtima de la libertad de los menores cuyas declaraciones habr\u00edan sido manipuladas. El tribunal <strong>tambi\u00e9n redujo el grado de responsabilidad penal de Rubio y Noguera<\/strong>, quienes dejaron de estar imputados como coautores y pasaron a ser \u201cpart\u00edcipes secundarios\u201d en algunos de los delitos investigados.<\/p>\n<p><strong>Soria sigue siendo el imputado m\u00e1s comprometido<\/strong>. A diferencia del resto, cuya prisi\u00f3n preventiva fue revocada tras las apelaciones presentadas ante la C\u00e1mara, \u00e9l todav\u00eda permanece detenido y enfrenta cargos adicionales por suministro gratuito de estupefacientes, atentado a la autoridad y usurpaci\u00f3n de t\u00edtulos, ya que se present\u00f3 como integrante de Interpol sin integrar ese organismo internacional.<\/p>\n<p><strong>Gallego consider\u00f3 que esta causa paralela podr\u00eda terminar antes de julio<\/strong>, mes en el que finalizar\u00eda la investigaci\u00f3n por la presunta sustracci\u00f3n y ocultamiento de Loan.<\/p>\n<h2>El caso por la desaparici\u00f3n de Loan Pe\u00f1a<\/h2>\n<p><strong>Loan Danilo Pe<\/strong><strong>\u00f1<\/strong><strong>a <\/strong>(nacido el 8 de mayo de 2019) est\u00e1 <strong>desaparecido desde el 13 de junio de 2024<\/strong> y se sospecha que fue v\u00edctima de un rapto o secuestro. La justicia eval\u00faa, como principal hip\u00f3tesis sobre su desaparici\u00f3n, el <strong>tr\u00e1fico de menores<\/strong>.<\/p>\n<p>El ni\u00f1o desapareci\u00f3 en<strong> <\/strong>9 de Julio, provincia de Corrientes, <strong>en una zona rural situada a metros de la casa de su abuela<\/strong>, cerca de un naranjal al que hab\u00eda ido acompa\u00f1ado por tres adultos y otros cinco ni\u00f1os, tras un almuerzo familiar al que hab\u00eda concurrido con su pap\u00e1.\u200b<\/p>\n<p>Tras 23 horas de la desaparici\u00f3n y luego de varios rastrillajes sin \u00e9xito, se activ\u00f3 la Alerta Sof\u00eda. Entre los sospechosos de estar implicados directa o indirectamente en la desaparici\u00f3n del menor se encuentran su t\u00edo, <strong>Antonio Ben\u00edtez<\/strong>; un amigo de Ben\u00edtez y su esposa (<strong>Daniel Ram\u00edrez y M\u00f3nica Millapi<\/strong>); la funcionaria municipal <strong>Mar\u00eda Victoria Caillava <\/strong>y su pareja<strong> Carlos P\u00e9rez<\/strong>; y <strong>Walter Maciel<\/strong>, un comisario acusado de posible encubrimiento.<\/p>\n<p><em>HM\/ML<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La C\u00e1mara Federal de Corrientes ratific\u00f3 este mi\u00e9rcoles 26 de marzo el procesamiento de los diez acusados de entorpecer la causa que investiga la presunta sustracci\u00f3n y ocultamiento de Loan Danilo Pe\u00f1a, quienes se presentaban como integrantes de la Fundaci\u00f3n Dupuy, sin estar vinculados de manera oficial a la organizaci\u00f3n pampeana ni contar con las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":100469,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[1115,480,488,315,1116],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/100468"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=100468"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/100468\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/100469"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=100468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=100468"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=100468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}