{"id":100363,"date":"2025-03-25T15:04:21","date_gmt":"2025-03-25T15:04:21","guid":{"rendered":"https:\/\/www.ole.com.ar\/basquet\/ginobili-manu-spurs-argentina-basquet-europa-all-25_0_2DfbKzKxxj.html"},"modified":"2025-03-25T15:04:21","modified_gmt":"2025-03-25T15:04:21","slug":"la-gloriosa-lista-donde-fue-incluido-manu-ginobili","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/03\/25\/la-gloriosa-lista-donde-fue-incluido-manu-ginobili\/","title":{"rendered":"La gloriosa lista donde fue incluido Manu Gin\u00f3bili"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/la-gloriosa-lista-donde-fue-incluido-manu-ginobili.jpg\"><\/p>\n<p><span class=\"createDate\">25\/03\/2025 12:04hs.<\/span><time class=\"modificatedDate\" datetime=\"2025-03-25T12:20:43-03:00\"> Actualizado al 25\/03\/2025 12:20hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"33.609375\">\n<p><strong><a href=\"https:\/\/www.ole.com.ar\/tema\/emanuel-ginobili.html\" title=\"Emanuel Gin\u00f3bili\" alt=\"Emanuel Gin\u00f3bili\" class=\"slug\">Emanuel Gin\u00f3bili<\/a><\/strong>, quien tuvo un gran paso por el <strong>Virtus Bologna<\/strong> (Kinder Bologna) y <strong>Viola Reggio Calabria<\/strong> de Italia, fue elegido en el <strong>Equipo All-25 de la Euroliga<\/strong>. Esta selecta lista est\u00e1 compuesta por <strong>los nombres m\u00e1s destacados<\/strong> que pasaron por la liga.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"36\">\n<p>La elecci\u00f3n se realiz\u00f3 mediante una votaci\u00f3n que combin\u00f3 el 10% de los votos del p\u00fablico, el 40% de entrenadores ganadores, el 10% de miembros de la prensa y el 40% de <strong>MVPs <\/strong>y miembros de los Equipos de la D\u00e9cada 2000-2010 y 2010-2020.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"52.182773109244\">\n<p>En la lista de los 25 hist\u00f3ricos de la Euroliga, adem\u00e1s de Manu, est\u00e1n <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/sergio-llull.html\" title=\"Sergio Llull\" alt=\"Sergio Llull\" class=\"slug\">Sergio Llull<\/a><\/strong>, Nando de Colo, Ramunas Siskauskas, Vassilis Spanoulis, Nikola Vujcic, Sergio Rodr\u00edguez, Dimitris Diamantidis, Mike James, Vasilije Micic, Anthony Parker, <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/luka-doncic.html\" title=\"Luka Doncic\" alt=\"Luka Doncic\" class=\"slug\">Luka Doncic<\/a><\/strong>, Walter Tavares, Milos Teodosic, Dejan Bodiroga, Georgios Printezis, Mike Batiste, Kyle Hines, <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/bogdan-bogdanovic.html\" title=\"Bogdan Bogdanovic\" alt=\"Bogdan Bogdanovic\" class=\"slug\">Bogdan Bogdanovic<\/a><\/strong>, Theo Papaloukas, Juan Carlos Navarro, <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/rudy-fernandez.html\" title=\"Rudy Fern\u00e1ndez\" alt=\"Rudy Fern\u00e1ndez\" class=\"slug\">Rudy Fern\u00e1ndez<\/a><\/strong>, Sarunas Jasikevicius, Shane Larkin y Kostas Sloukas.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"Manu Gin\u00f3bili con la del Kinder Bolonia.\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/la-gloriosa-lista-donde-fue-incluido-manu-ginobili-2.jpg\"><span class=\"epigraphe\">Manu Gin\u00f3bili con la del Kinder Bolonia.<\/span><\/div>\n<p><h2><strong>Los n\u00fameros de Gin\u00f3bili en Europa<\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"37.799352750809\">\n<p>Manu brill\u00f3 en la Euroliga entre 2000 y 2002, antes de dar el salto a la NBA con los <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/san-antonio-spurs.html\" title=\"San Antonio Spurs\" alt=\"San Antonio Spurs\" class=\"slug\">San Antonio Spurs<\/a><\/strong> y ganar cuatro anillos. Con el Virtus Bologna, fue campe\u00f3n en la temporada 2000-01, donde promedi\u00f3 <strong>15.2 puntos, 4.1 rebotes, 2 asistencias y 2.9 robos en 22 partidos<\/strong>. Gin\u00f3bili fue el MVP de las finales.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"39\">\n<p>En la temporada 2001-02, llev\u00f3 al equipo nuevamente a la final, aunque en esta ocasi\u00f3n cayeron ante Panathinaikos. Hab\u00eda promediado <strong>15.9 puntos, 3.8 rebotes, 3 asistencias y 2.5 robos en 22 partidos<\/strong>, integrando el mejor quinteto de la Euroliga.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"Ginobili enfrentando a Oberto. (ap) \" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/la-gloriosa-lista-donde-fue-incluido-manu-ginobili-3.jpg\"><span class=\"epigraphe\">Ginobili enfrentando a Oberto. (ap) <\/span><\/div>\n<p><h2><strong>Los n\u00fameros de Gin\u00f3bili en la NBA<\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"37.059405940594\">\n<p>Gin\u00f3bili sin dudas es uno de los mejores jugadores de la historia de los Spurs, incluso algunos lo ubican dentro de los mejores 75 de la NBA. Si bien fue seleccionado como n\u00famero 57 en el Draft de 1999, no debut\u00f3 hasta 2002, momento en el que se convirti\u00f3 r\u00e1pidamente en una figura clave al ganar el anillo en su primera temporada. All\u00ed form\u00f3 un inolvidable Big Three con <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/tim-duncan.html\" title=\"Tim Duncan\" alt=\"Tim Duncan\" class=\"slug\">Tim Duncan<\/a><\/strong> y Tony Parker.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"40\">\n<p>Durante su carrera, el escolta argentino fue crucial en los cuatro campeonatos obtenidos entre 2003 y 2014. <strong>Con promedios de 13.3 puntos, 3.5 rebotes y 3.8 asistencias en 1,057 partidos<\/strong>, es el l\u00edder hist\u00f3rico en robos y cuarto en asistencias de la franquicia. Adem\u00e1s, fue dos veces All-Star y el Mejor Sexto Hombre en 2008. <strong>Su m\u00edtico n\u00famero 20 fue retirado por la franquicia<\/strong>.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"Gin\u00f3bili, junto a Oberto, \u00fanicos argentinos con anillo de la NBA. (ap)\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/la-gloriosa-lista-donde-fue-incluido-manu-ginobili-4.jpg\"><span class=\"epigraphe\">Gin\u00f3bili, junto a Oberto, \u00fanicos argentinos con anillo de la NBA. (ap)<\/span><\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"Liga Nacional de B\u00e1squet: triunfos de Ober\u00e1, Gimnasia y Atenas\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/la-gloriosa-lista-donde-fue-incluido-manu-ginobili-5.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Liga Nacional de B\u00e1squet: triunfos de Ober\u00e1, Gimnasia y Atenas<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"La jugada futbolera de Jayson Tatum que le vali\u00f3 ser comparado con Messi\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/la-gloriosa-lista-donde-fue-incluido-manu-ginobili-6.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>La jugada futbolera de Jayson Tatum que le vali\u00f3 ser comparado con Messi<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Liga Nacional: Obras le gan\u00f3 a Boca en suplementario\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/la-gloriosa-lista-donde-fue-incluido-manu-ginobili-7.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Liga Nacional: Obras le gan\u00f3 a Boca en suplementario<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>25\/03\/2025 12:04hs. Actualizado al 25\/03\/2025 12:20hs. Emanuel Gin\u00f3bili, quien tuvo un gran paso por el Virtus Bologna (Kinder Bologna) y Viola Reggio Calabria de Italia, fue elegido en el Equipo All-25 de la Euroliga. Esta selecta lista est\u00e1 compuesta por los nombres m\u00e1s destacados que pasaron por la liga. La elecci\u00f3n se realiz\u00f3 mediante una [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":100364,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/100363"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=100363"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/100363\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/100364"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=100363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=100363"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=100363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}