{"id":100199,"date":"2025-03-23T14:08:01","date_gmt":"2025-03-23T14:08:01","guid":{"rendered":"https:\/\/www.ole.com.ar\/futbol-internacional\/eliminatorias\/accidente-fatal-muerto-estadio-entreno-brasil-argentina_0_dDfT0CtDiE.html"},"modified":"2025-03-23T14:08:01","modified_gmt":"2025-03-23T14:08:01","slug":"accidente-fatal-con-un-muerto-en-el-estadio-donde-se-entreno-brasil-antes-del-duelo-con-argentina","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/03\/23\/accidente-fatal-con-un-muerto-en-el-estadio-donde-se-entreno-brasil-antes-del-duelo-con-argentina\/","title":{"rendered":"Accidente fatal con un muerto en el estadio donde se entren\u00f3 Brasil antes del duelo con Argentina"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/accidente-fatal-con-un-muerto-en-el-estadio-donde-se-entreno-brasil-antes-del-duelo-con-argentina.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2025-03-23T11:08:01-03:00\">23\/03\/2025 11:08hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"36.380681818182\">\n<p><strong>Un tr\u00e1gico accidente afect\u00f3 el \u00faltimo entrenamiento de la selecci\u00f3n de <a href=\"https:\/\/www.ole.com.ar\/tema\/brasil.html\" title=\"Brasil\" alt=\"Brasil\" class=\"slug\">Brasil<\/a>, <\/strong>que se prepara para visitar a la <a href=\"https:\/\/www.ole.com.ar\/tema\/seleccion-argentina.html\" title=\"Selecci\u00f3n Argentina\" alt=\"Selecci\u00f3n Argentina\" class=\"slug\">Argentina <\/a>el pr\u00f3ximo martes. Un operario que trabajaba montando un escenario para un evento en el estadio Mane Garrincha sufri\u00f3 una descarga el\u00e9ctrica y, pese a que fue atendido r\u00e1pidamente, <strong>no pudieron reanimarlo y perdi\u00f3 la vida<\/strong>.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p>Al hombre, de 32 a\u00f1os, le practicaron masaje cardiopulmonar pero finalmente falleci\u00f3 casi una hora despu\u00e9s. Esto <strong>retras\u00f3 un buen rato el arranque del entrenamiento de la selecci\u00f3n brasile\u00f1a,<\/strong> que tuvo lugar en el mismo estadio, ubicado en la capital Brasilia. <\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"35\">\n<p>La Verdeamarela volver\u00e1 a entrenarse en el Man\u00e9 Garrincha este domingo y el lunes por la ma\u00f1ana, antes de viajar hacia Buenos Aires para el duelo del martes contra la Selecci\u00f3n en el estadio Monumental.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"Brasil se entren\u00f3 una hora m\u00e1s tarde por el tr\u00e1gico accidente. (EFE).\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/accidente-fatal-con-un-muerto-en-el-estadio-donde-se-entreno-brasil-antes-del-duelo-con-argentina-2.jpg\"><span class=\"epigraphe\">Brasil se entren\u00f3 una hora m\u00e1s tarde por el tr\u00e1gico accidente. (EFE).<\/span><\/div>\n<p><h2>Brasil y un equipo lleno de bajas<\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"34\">\n<p>Una vez que Brasil sali\u00f3 al campo de juego, los futbolistas realizaron ejercicios con pelota y lo que m\u00e1s llam\u00f3 la atenci\u00f3n fue <strong>la ausencia de <a href=\"https:\/\/www.ole.com.ar\/tema\/vinicius.html\" title=\"Vinicius\" alt=\"Vinicius\" class=\"slug\">Vin\u00edcius J\u00fanior<\/a><\/strong>. El autor del gol ag\u00f3nico para ganarle a Colombia el jueves pasado ni siquiera se puso los botines y apenas dio unas vueltas por el c\u00e9sped. <\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"Vini charla con el t\u00e9cnico Dorival. Llega entre algodones al martes (EFE).\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/accidente-fatal-con-un-muerto-en-el-estadio-donde-se-entreno-brasil-antes-del-duelo-con-argentina-3.jpg\"><span class=\"epigraphe\">Vini charla con el t\u00e9cnico Dorival. Llega entre algodones al martes (EFE).<\/span><\/div>\n<div class=\"custom-text \" readability=\"40.116923076923\">\n<p>Si participaron Joao Gomes, Weverton, Beraldo y Ederson, los cuatro convocados de urgencia por <a href=\"https:\/\/www.ole.com.ar\/tema\/dorival-junior.html\" title=\"Dorival J\u00fanior\" alt=\"Dorival J\u00fanior\" class=\"slug\">Dorival <\/a>ante las bajas que tiene en su equipo. Dos de ellos ser\u00edan titular el martes vs. la Scaloneta, teniendo en cuenta que <strong>hay al menos cuatro bajas confirmadas: <\/strong>el arquero Alisson, Gabriel Magalhaes, Bruno Guimaraes y Gerson.<\/p>\n<\/div>\n<p><h2>El Cuerpo de Bomberos Militares confirm\u00f3 la muerte<\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"34\">\n<p>\u201cEl Cuerpo Militar de Bomberos del Distrito Federal (CBMDF) respondi\u00f3 a este incidente a las 16:11 horas del d\u00eda 22\/03\/2025 comprometiendo 04 (cuatro) veh\u00edculos. El accidente ocurri\u00f3 en el Estadio Man\u00e9 Garrincha.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"40\">\n<p>\u00abAl llegar al lugar, el equipo que atendi\u00f3 el llamado de emergencia encontr\u00f3 al se\u00f1or R. P. C, de 32 a\u00f1os, en el suelo, inconsciente, luego de sufrir una descarga el\u00e9ctrica. Al ser evaluado por nuestros rescatistas, se constat\u00f3 que se encontraba en <strong>paro cardiorrespiratorio.<\/strong><\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p>Inmediatamente, los militares iniciaron protocolos de reanimaci\u00f3n cardiopulmonar, sin embargo, luego de aproximadamente una hora de maniobras, la v\u00edctima no reaccion\u00f3 y su muerte fue declarada por el m\u00e9dico de rescate a\u00e9reo del CBMDF.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"32\">\n<p>\u00abEl PCDF fue llamado al lugar. No sabemos en qu\u00e9 circunstancias se produjo el accidente\u00bb.<\/p>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"Selecci\u00f3n: con De Paul, el posible 11 de Argentina para enfrentar a Brasil\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/accidente-fatal-con-un-muerto-en-el-estadio-donde-se-entreno-brasil-antes-del-duelo-con-argentina-4.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Selecci\u00f3n: con De Paul, el posible 11 de Argentina para enfrentar a Brasil<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Especial de Dibu: c\u00f3mo cambi\u00f3 la historia en 50 partidos en la Selecci\u00f3n \" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/accidente-fatal-con-un-muerto-en-el-estadio-donde-se-entreno-brasil-antes-del-duelo-con-argentina-5.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Especial de Dibu: c\u00f3mo cambi\u00f3 la historia en 50 partidos en la Selecci\u00f3n <\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Por qu\u00e9 esta Selecci\u00f3n es el equipo del pueblo\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/accidente-fatal-con-un-muerto-en-el-estadio-donde-se-entreno-brasil-antes-del-duelo-con-argentina-6.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Por qu\u00e9 esta Selecci\u00f3n es el equipo del pueblo<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>23\/03\/2025 11:08hs. Un tr\u00e1gico accidente afect\u00f3 el \u00faltimo entrenamiento de la selecci\u00f3n de Brasil, que se prepara para visitar a la Argentina el pr\u00f3ximo martes. Un operario que trabajaba montando un escenario para un evento en el estadio Mane Garrincha sufri\u00f3 una descarga el\u00e9ctrica y, pese a que fue atendido r\u00e1pidamente, no pudieron reanimarlo y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":100200,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/100199"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=100199"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/100199\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/100200"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=100199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=100199"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=100199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}